{"id":2798,"count":12,"description":"","link":"https:\/\/lpg-view.com\/de\/tag\/lpg-ansicht\/","name":"LPG Ansicht","slug":"lpg-ansicht","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Archiwa LPG Ansicht - LPG View<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lpg-view.com\/de\/tag\/lpg-ansicht\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archiwa LPG Ansicht - LPG View\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lpg-view.com\/de\/tag\/lpg-ansicht\/\" \/>\n<meta property=\"og:site_name\" content=\"LPG View\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/lpg-view.com\/de\/tag\/lpg-ansicht\/\",\"url\":\"https:\/\/lpg-view.com\/de\/tag\/lpg-ansicht\/\",\"name\":\"Archiwa LPG Ansicht - LPG View\",\"isPartOf\":{\"@id\":\"https:\/\/lpg-view.com\/de\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/lpg-view.com\/de\/tag\/lpg-ansicht\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lpg-view.com\/de\/tag\/lpg-ansicht\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/lpg-view.com\/de\/startseite\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LPG Ansicht\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lpg-view.com\/de\/#website\",\"url\":\"https:\/\/lpg-view.com\/de\/\",\"name\":\"LPG View\",\"description\":\"LPG View - wszystko o twoim zbiorniku\",\"publisher\":{\"@id\":\"https:\/\/lpg-view.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lpg-view.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/lpg-view.com\/de\/#organization\",\"name\":\"LPG View\",\"url\":\"https:\/\/lpg-view.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/lpg-view.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/lpg-view.com\/wp-content\/uploads\/2022\/04\/lpg-logo.svg\",\"contentUrl\":\"https:\/\/lpg-view.com\/wp-content\/uploads\/2022\/04\/lpg-logo.svg\",\"width\":146,\"height\":20,\"caption\":\"LPG View\"},\"image\":{\"@id\":\"https:\/\/lpg-view.com\/de\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archiwa LPG Ansicht - LPG View","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lpg-view.com\/de\/tag\/lpg-ansicht\/","og_locale":"de_DE","og_type":"article","og_title":"Archiwa LPG Ansicht - LPG View","og_url":"https:\/\/lpg-view.com\/de\/tag\/lpg-ansicht\/","og_site_name":"LPG View","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/lpg-view.com\/de\/tag\/lpg-ansicht\/","url":"https:\/\/lpg-view.com\/de\/tag\/lpg-ansicht\/","name":"Archiwa LPG Ansicht - LPG View","isPartOf":{"@id":"https:\/\/lpg-view.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/lpg-view.com\/de\/tag\/lpg-ansicht\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/lpg-view.com\/de\/tag\/lpg-ansicht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/lpg-view.com\/de\/startseite\/"},{"@type":"ListItem","position":2,"name":"LPG Ansicht"}]},{"@type":"WebSite","@id":"https:\/\/lpg-view.com\/de\/#website","url":"https:\/\/lpg-view.com\/de\/","name":"LPG View","description":"LPG View - wszystko o twoim zbiorniku","publisher":{"@id":"https:\/\/lpg-view.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lpg-view.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/lpg-view.com\/de\/#organization","name":"LPG View","url":"https:\/\/lpg-view.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/lpg-view.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/lpg-view.com\/wp-content\/uploads\/2022\/04\/lpg-logo.svg","contentUrl":"https:\/\/lpg-view.com\/wp-content\/uploads\/2022\/04\/lpg-logo.svg","width":146,"height":20,"caption":"LPG View"},"image":{"@id":"https:\/\/lpg-view.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lpg-view.com\/de\/wp-json\/wp\/v2\/tags\/2798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lpg-view.com\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/lpg-view.com\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/lpg-view.com\/de\/wp-json\/wp\/v2\/posts?tags=2798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}